{"id":2649,"date":"2023-05-01T09:47:40","date_gmt":"2023-05-01T09:47:40","guid":{"rendered":"https:\/\/agenda.poscosecha.com\/events\/prognosfruit-2021\/"},"modified":"2024-02-16T17:25:54","modified_gmt":"2024-02-16T16:25:54","slug":"prognosfruit-peras-manzanas2023","status":"publish","type":"mec-events","link":"https:\/\/agenda.poscosecha.com\/en\/eventos\/prognosfruit-peras-manzanas2023\/","title":{"rendered":"Prognosfruit 2024"},"content":{"rendered":"<p><a href=\"http:\/\/wapa-association.org\/asp\/index.asp\" target=\"_blank\" rel=\"noopener\">Organiza: The Worold Apple and Pear Association<\/a><\/p>\n<p>PROGNOSFRUIT is the world\u2019s leading annual event for the fruit industry. At this conference, the World Apple and Pear Association (WAPA) announces the apple and pear production forecast, and fruit market trends in the EU and outside are discussed. The conference brings together producers, processors and traders from various European countries and beyond.<\/p>\n<p>Prognosfruit se basa en una larga experiencia reuniendo a la industria europea de manzanas y peras. Prognosfruit est\u00e1 atrayendo a productores, procesadores y comerciantes de toda Europa y m\u00e1s all\u00e1, y ofrece una oportunidad de establecer contactos para los responsables de la toma de decisiones que asisten a la conferencia. Adem\u00e1s de la conferencia, tambi\u00e9n hay una visita t\u00e9cnica y varios eventos sociales para reforzar la red y los contactos entre la comunidad europea de manzanas y peras.<\/p>\n<p>wapa@wapa-association.org<\/p>","protected":false},"excerpt":{"rendered":"<p>El Prognosfruit de la Asociaci\u00f3n Mundial de Manzanas y Peras (WAPA) anuncia las previsiones de producci\u00f3n de manzanas y peras y las tendencias del mercado <\/p>","protected":false},"author":1,"featured_media":3993,"template":"","tags":[],"mec_category":[20],"class_list":["post-2649","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","mec_category-congresos-forums-jornadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prognosfruit-Congresos-AGENDA Poscosecha<\/title>\n<meta name=\"description\" content=\"Prognosfruit es el evento l\u00edder en la industria frut\u00edcola. La WAPA anuncia el pron\u00f3stico de producci\u00f3n de manzanas y peras\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agenda.poscosecha.com\/en\/eventos\/prognosfruit-peras-manzanas2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prognosfruit-Congresos-AGENDA Poscosecha\" \/>\n<meta property=\"og:description\" content=\"Prognosfruit es el evento l\u00edder en la industria frut\u00edcola. La WAPA anuncia el pron\u00f3stico de producci\u00f3n de manzanas y peras\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agenda.poscosecha.com\/en\/eventos\/prognosfruit-peras-manzanas2023\/\" \/>\n<meta property=\"og:site_name\" content=\"AGENDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Poscosecha.Postharvest\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-16T16:25:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agenda.poscosecha.com\/wp-content\/uploads\/2023\/05\/Prognosfruit-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"322\" \/>\n\t<meta property=\"og:image:height\" content=\"157\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@poscosecha\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agenda.poscosecha.com\\\/eventos\\\/prognosfruit-peras-manzanas2023\\\/\",\"url\":\"https:\\\/\\\/agenda.poscosecha.com\\\/eventos\\\/prognosfruit-peras-manzanas2023\\\/\",\"name\":\"Prognosfruit-Congresos-AGENDA Poscosecha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agenda.poscosecha.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agenda.poscosecha.com\\\/eventos\\\/prognosfruit-peras-manzanas2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agenda.poscosecha.com\\\/eventos\\\/prognosfruit-peras-manzanas2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agenda.poscosecha.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Prognosfruit-2.jpg\",\"datePublished\":\"2023-05-01T09:47:40+00:00\",\"dateModified\":\"2024-02-16T16:25:54+00:00\",\"description\":\"Prognosfruit es el evento l\u00edder en la industria frut\u00edcola. La WAPA anuncia el pron\u00f3stico de producci\u00f3n de manzanas y peras\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agenda.poscosecha.com\\\/eventos\\\/prognosfruit-peras-manzanas2023\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agenda.poscosecha.com\\\/eventos\\\/prognosfruit-peras-manzanas2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agenda.poscosecha.com\\\/eventos\\\/prognosfruit-peras-manzanas2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agenda.poscosecha.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Prognosfruit-2.jpg\",\"contentUrl\":\"https:\\\/\\\/agenda.poscosecha.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Prognosfruit-2.jpg\",\"width\":322,\"height\":157},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agenda.poscosecha.com\\\/eventos\\\/prognosfruit-peras-manzanas2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agenda.poscosecha.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/agenda.poscosecha.com\\\/eventos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prognosfruit 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agenda.poscosecha.com\\\/#website\",\"url\":\"https:\\\/\\\/agenda.poscosecha.com\\\/\",\"name\":\"Agenda de Eventos\",\"description\":\"Conectando comunidades poscosecha globales\",\"publisher\":{\"@id\":\"https:\\\/\\\/agenda.poscosecha.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agenda.poscosecha.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agenda.poscosecha.com\\\/#organization\",\"name\":\"Agenda de Eventos\",\"url\":\"https:\\\/\\\/agenda.poscosecha.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agenda.poscosecha.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agenda.poscosecha.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-Agenda-logo-vs-1.png\",\"contentUrl\":\"https:\\\/\\\/agenda.poscosecha.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-Agenda-logo-vs-1.png\",\"width\":512,\"height\":512,\"caption\":\"Agenda de Eventos\"},\"image\":{\"@id\":\"https:\\\/\\\/agenda.poscosecha.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Poscosecha.Postharvest\\\/\",\"https:\\\/\\\/x.com\\\/poscosecha\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/poscosecha.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prognosfruit-Congresos-AGENDA Poscosecha","description":"Prognosfruit es el evento l\u00edder en la industria frut\u00edcola. La WAPA anuncia el pron\u00f3stico de producci\u00f3n de manzanas y peras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agenda.poscosecha.com\/en\/eventos\/prognosfruit-peras-manzanas2023\/","og_locale":"en_GB","og_type":"article","og_title":"Prognosfruit-Congresos-AGENDA Poscosecha","og_description":"Prognosfruit es el evento l\u00edder en la industria frut\u00edcola. La WAPA anuncia el pron\u00f3stico de producci\u00f3n de manzanas y peras","og_url":"https:\/\/agenda.poscosecha.com\/en\/eventos\/prognosfruit-peras-manzanas2023\/","og_site_name":"AGENDA","article_publisher":"https:\/\/www.facebook.com\/Poscosecha.Postharvest\/","article_modified_time":"2024-02-16T16:25:54+00:00","og_image":[{"width":322,"height":157,"url":"https:\/\/agenda.poscosecha.com\/wp-content\/uploads\/2023\/05\/Prognosfruit-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@poscosecha","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/agenda.poscosecha.com\/eventos\/prognosfruit-peras-manzanas2023\/","url":"https:\/\/agenda.poscosecha.com\/eventos\/prognosfruit-peras-manzanas2023\/","name":"Prognosfruit-Congresos-AGENDA Poscosecha","isPartOf":{"@id":"https:\/\/agenda.poscosecha.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agenda.poscosecha.com\/eventos\/prognosfruit-peras-manzanas2023\/#primaryimage"},"image":{"@id":"https:\/\/agenda.poscosecha.com\/eventos\/prognosfruit-peras-manzanas2023\/#primaryimage"},"thumbnailUrl":"https:\/\/agenda.poscosecha.com\/wp-content\/uploads\/2023\/05\/Prognosfruit-2.jpg","datePublished":"2023-05-01T09:47:40+00:00","dateModified":"2024-02-16T16:25:54+00:00","description":"Prognosfruit es el evento l\u00edder en la industria frut\u00edcola. La WAPA anuncia el pron\u00f3stico de producci\u00f3n de manzanas y peras","breadcrumb":{"@id":"https:\/\/agenda.poscosecha.com\/eventos\/prognosfruit-peras-manzanas2023\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agenda.poscosecha.com\/eventos\/prognosfruit-peras-manzanas2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agenda.poscosecha.com\/eventos\/prognosfruit-peras-manzanas2023\/#primaryimage","url":"https:\/\/agenda.poscosecha.com\/wp-content\/uploads\/2023\/05\/Prognosfruit-2.jpg","contentUrl":"https:\/\/agenda.poscosecha.com\/wp-content\/uploads\/2023\/05\/Prognosfruit-2.jpg","width":322,"height":157},{"@type":"BreadcrumbList","@id":"https:\/\/agenda.poscosecha.com\/eventos\/prognosfruit-peras-manzanas2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agenda.poscosecha.com\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/agenda.poscosecha.com\/eventos\/"},{"@type":"ListItem","position":3,"name":"Prognosfruit 2024"}]},{"@type":"WebSite","@id":"https:\/\/agenda.poscosecha.com\/#website","url":"https:\/\/agenda.poscosecha.com\/","name":"Agenda de Eventos","description":"Conectando comunidades poscosecha globales","publisher":{"@id":"https:\/\/agenda.poscosecha.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agenda.poscosecha.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/agenda.poscosecha.com\/#organization","name":"Agenda de Eventos","url":"https:\/\/agenda.poscosecha.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agenda.poscosecha.com\/#\/schema\/logo\/image\/","url":"https:\/\/agenda.poscosecha.com\/wp-content\/uploads\/2023\/06\/cropped-Agenda-logo-vs-1.png","contentUrl":"https:\/\/agenda.poscosecha.com\/wp-content\/uploads\/2023\/06\/cropped-Agenda-logo-vs-1.png","width":512,"height":512,"caption":"Agenda de Eventos"},"image":{"@id":"https:\/\/agenda.poscosecha.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Poscosecha.Postharvest\/","https:\/\/x.com\/poscosecha","https:\/\/www.linkedin.com\/company\/poscosecha.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/agenda.poscosecha.com\/en\/wp-json\/wp\/v2\/mec-events\/2649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenda.poscosecha.com\/en\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/agenda.poscosecha.com\/en\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/agenda.poscosecha.com\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agenda.poscosecha.com\/en\/wp-json\/wp\/v2\/media\/3993"}],"wp:attachment":[{"href":"https:\/\/agenda.poscosecha.com\/en\/wp-json\/wp\/v2\/media?parent=2649"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agenda.poscosecha.com\/en\/wp-json\/wp\/v2\/tags?post=2649"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/agenda.poscosecha.com\/en\/wp-json\/wp\/v2\/mec_category?post=2649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}